{"id":5244,"date":"2022-04-05T11:11:52","date_gmt":"2022-04-05T10:11:52","guid":{"rendered":"https:\/\/www.collefrisio.it\/gallery\/"},"modified":"2022-04-05T11:22:34","modified_gmt":"2022-04-05T10:22:34","slug":"gallery","status":"publish","type":"page","link":"https:\/\/www.collefrisio.it\/en\/gallery\/","title":{"rendered":"Gallery"},"content":{"rendered":"<p>[vc_row el_class=&#8221;gallery-first-row&#8221;][vc_column offset=&#8221;vc_col-lg-offset-1 vc_col-lg-10&#8243;]<div class=\"mkdf-section-title-holder  mkdf-st-standard mkdf-st-title-left mkdf-st-normal-space \" style=\"text-align: center\">\n\t<div class=\"mkdf-st-inner\">\n\t\t\t\t\t<span class=\"mkdf-st-subtitle\" >\n\t\t\t\tAmedeo De Luca e Antonio Patricelli\t\t\t<\/span>\n\t\t\t\t\t\t\t<h2 class=\"mkdf-st-title\" >\n\t\t\t\tFounders Interviews \t\t\t<\/h2>\n\t\t\t\t\t<\/div>\n<\/div>[vc_empty_space][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<video src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/01-collefrisio-intervista-amedeo-de-luca-eng.mp4\" poster=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-logo-video.jpeg\" controls=\"controls\" width=\"100%\" height=\"auto\"><\/video><\/p>\n<h4 style=\"text-align: left;\">Interview to Amedeo De Luca &#8211; Founder<\/h4>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<video src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/02-collefrisio-intervista-antonio-patricelli-eng-01.mp4\" poster=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-logo-video.jpeg\" controls=\"controls\" width=\"100%\" height=\"auto\"><\/video><\/p>\n<h4>Interview with Antonio Patricelli part 1 &#8211; Founder<\/h4>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<video src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/03-collefrisio-intervista-antonio-patricelli-eng-02.mp4\" poster=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-logo-video.jpeg\" controls=\"controls\" width=\"100%\" height=\"auto\"><\/video><\/p>\n<h4>Interview to Antonio Patricelli part 2 &#8211; Founder<\/h4>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row row_content_width=&#8221;grid&#8221; el_class=&#8221;gallery-sec-row&#8221;][vc_column]<div class=\"mkdf-section-title-holder  mkdf-st-standard mkdf-st-title-left mkdf-st-normal-space \" style=\"text-align: center\">\n\t<div class=\"mkdf-st-inner\">\n\t\t\t\t\t\t\t<h2 class=\"mkdf-st-title\" >\n\t\t\t\tHarvest 2021\t\t\t<\/h2>\n\t\t\t\t\t<\/div>\n<\/div>[vc_empty_space]<div class=\"mkdf-image-gallery  mkdf-ig-carousel-type mkdf-three-columns mkdf-tiny-space mkdf-has-shadow mkdf-image-behavior-lightbox  \">\n\t<div class=\"mkdf-ig-slider mkdf-owl-slider\" data-number-of-items=\"2\" data-enable-loop=\"yes\" data-enable-autoplay=\"yes\" data-slider-speed=\"5000\" data-slider-speed-animation=\"600\" data-slider-padding=\"no\" data-enable-navigation=\"yes\" data-enable-pagination=\"yes\">\n\t\t\t\t\t<div class=\"mkdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox mkdf-block-drag-link\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-01.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-48]\" title=\"collefrisio-gallery-vendemmi-2021-01\">\n\t\t\t\t\t\t\t\t\t<img width=\"1280\" height=\"852\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-01.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-01.jpg 1280w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-01-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-01-1024x682.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-01-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mkdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox mkdf-block-drag-link\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-02.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-48]\" title=\"collefrisio-gallery-vendemmi-2021-02\">\n\t\t\t\t\t\t\t\t\t<img width=\"1280\" height=\"852\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-02.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-02.jpg 1280w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-02-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-02-1024x682.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-02-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mkdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox mkdf-block-drag-link\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-03.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-48]\" title=\"collefrisio-gallery-vendemmi-2021-03\">\n\t\t\t\t\t\t\t\t\t<img width=\"1280\" height=\"852\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-03.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-03.jpg 1280w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-03-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-03-1024x682.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-03-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mkdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox mkdf-block-drag-link\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-04.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-48]\" title=\"collefrisio-gallery-vendemmi-2021-04\">\n\t\t\t\t\t\t\t\t\t<img width=\"1280\" height=\"852\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-04.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-04.jpg 1280w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-04-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-04-1024x682.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-04-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mkdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox mkdf-block-drag-link\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-05.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-48]\" title=\"collefrisio-gallery-vendemmi-2021-05\">\n\t\t\t\t\t\t\t\t\t<img width=\"1280\" height=\"852\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-05.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-05.jpg 1280w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-05-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-05-1024x682.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-05-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mkdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox mkdf-block-drag-link\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-014.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-48]\" title=\"collefrisio-gallery-vendemmi-2021-014\">\n\t\t\t\t\t\t\t\t\t<img width=\"1280\" height=\"852\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-014.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-014.jpg 1280w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-014-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-014-1024x682.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-014-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mkdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox mkdf-block-drag-link\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-015.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-48]\" title=\"collefrisio-gallery-vendemmi-2021-015\">\n\t\t\t\t\t\t\t\t\t<img width=\"1280\" height=\"852\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-015.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-015.jpg 1280w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-015-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-015-1024x682.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-015-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mkdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox mkdf-block-drag-link\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-016.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-48]\" title=\"collefrisio-gallery-vendemmi-2021-016\">\n\t\t\t\t\t\t\t\t\t<img width=\"1280\" height=\"852\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-016.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-016.jpg 1280w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-016-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-016-1024x682.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-016-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mkdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox mkdf-block-drag-link\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-017.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-48]\" title=\"collefrisio-gallery-vendemmi-2021-017\">\n\t\t\t\t\t\t\t\t\t<img width=\"1280\" height=\"852\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-017.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-017.jpg 1280w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-017-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-017-1024x682.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-017-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mkdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox mkdf-block-drag-link\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-06.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-48]\" title=\"collefrisio-gallery-vendemmi-2021-06\">\n\t\t\t\t\t\t\t\t\t<img width=\"1280\" height=\"852\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-06.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-06.jpg 1280w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-06-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-06-1024x682.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-06-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mkdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox mkdf-block-drag-link\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-07.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-48]\" title=\"collefrisio-gallery-vendemmi-2021-07\">\n\t\t\t\t\t\t\t\t\t<img width=\"1280\" height=\"852\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-07.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-07.jpg 1280w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-07-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-07-1024x682.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-07-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mkdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox mkdf-block-drag-link\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-08.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-48]\" title=\"collefrisio-gallery-vendemmi-2021-08\">\n\t\t\t\t\t\t\t\t\t<img width=\"1280\" height=\"852\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-08.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-08.jpg 1280w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-08-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-08-1024x682.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-08-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mkdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox mkdf-block-drag-link\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-09.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-48]\" title=\"collefrisio-gallery-vendemmi-2021-09\">\n\t\t\t\t\t\t\t\t\t<img width=\"1280\" height=\"852\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-09.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-09.jpg 1280w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-09-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-09-1024x682.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-09-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mkdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox mkdf-block-drag-link\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-010.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-48]\" title=\"collefrisio-gallery-vendemmi-2021-010\">\n\t\t\t\t\t\t\t\t\t<img width=\"1280\" height=\"852\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-010.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-010.jpg 1280w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-010-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-010-1024x682.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-010-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mkdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox mkdf-block-drag-link\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-011.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-48]\" title=\"collefrisio-gallery-vendemmi-2021-011\">\n\t\t\t\t\t\t\t\t\t<img width=\"1280\" height=\"852\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-011.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-011.jpg 1280w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-011-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-011-1024x682.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-011-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mkdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox mkdf-block-drag-link\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-012.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-48]\" title=\"collefrisio-gallery-vendemmi-2021-012\">\n\t\t\t\t\t\t\t\t\t<img width=\"1280\" height=\"852\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-012.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-012.jpg 1280w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-012-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-012-1024x682.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-012-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mkdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox mkdf-block-drag-link\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-013.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-48]\" title=\"collefrisio-gallery-vendemmi-2021-013\">\n\t\t\t\t\t\t\t\t\t<img width=\"1280\" height=\"852\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-013.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-013.jpg 1280w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-013-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-013-1024x682.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/04\/collefrisio-gallery-vendemmi-2021-013-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>[\/vc_column][\/vc_row][vc_row el_class=&#8221;gallery-third-row&#8221;][vc_column offset=&#8221;vc_col-lg-offset-1 vc_col-lg-10&#8243;]<div class=\"mkdf-section-title-holder  mkdf-st-standard mkdf-st-title-left mkdf-st-normal-space \" style=\"text-align: center\">\n\t<div class=\"mkdf-st-inner\">\n\t\t\t\t\t\t\t<h2 class=\"mkdf-st-title\" >\n\t\t\t\tThe winery\t\t\t<\/h2>\n\t\t\t\t\t<\/div>\n<\/div>[vc_empty_space]<div class=\"mkdf-image-gallery mkdf-grid-list mkdf-grid-masonry-list mkdf-disable-bottom-space  mkdf-ig-masonry-type mkdf-three-columns mkdf-tiny-space mkdf-has-shadow mkdf-image-behavior-lightbox  \">\n\t<div class=\"mkdf-ig-inner mkdf-outer-space mkdf-masonry-list-wrapper\">\n\t\t<div class=\"mkdf-masonry-grid-sizer\"><\/div>\n\t\t<div class=\"mkdf-masonry-grid-gutter\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"mkdf-ig-image mkdf-item-space \">\n\t\t\t\t<div class=\"mkdf-ig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-12.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-178]\" title=\"collefrisio-gallery-12\">\n\t\t\t\t\t\t\t\t\t\t\t<img width=\"1209\" height=\"768\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-12.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-12.jpg 1209w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-12-300x191.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-12-1024x650.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-12-768x488.jpg 768w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-12-600x381.jpg 600w\" sizes=\"(max-width: 1209px) 100vw, 1209px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"mkdf-ig-image mkdf-item-space \">\n\t\t\t\t<div class=\"mkdf-ig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/01\/collefrisio-gallery-15.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-178]\" title=\"collefrisio-gallery-15\">\n\t\t\t\t\t\t\t\t\t\t\t<img width=\"1500\" height=\"449\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/01\/collefrisio-gallery-15.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/01\/collefrisio-gallery-15.jpg 1500w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/01\/collefrisio-gallery-15-300x90.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/01\/collefrisio-gallery-15-1024x307.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/01\/collefrisio-gallery-15-768x230.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"mkdf-ig-image mkdf-item-space \">\n\t\t\t\t<div class=\"mkdf-ig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-01.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-178]\" title=\"collefrisio-gallery-01\">\n\t\t\t\t\t\t\t\t\t\t\t<img width=\"1500\" height=\"998\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-01.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-01.jpg 1500w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-01-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-01-1024x681.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-01-768x511.jpg 768w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-01-600x399.jpg 600w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"mkdf-ig-image mkdf-item-space \">\n\t\t\t\t<div class=\"mkdf-ig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-11.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-178]\" title=\"collefrisio-gallery-11\">\n\t\t\t\t\t\t\t\t\t\t\t<img width=\"1366\" height=\"768\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-11.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-11.jpg 1366w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-11-300x169.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-11-1024x576.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-11-768x432.jpg 768w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-11-600x337.jpg 600w\" sizes=\"(max-width: 1366px) 100vw, 1366px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"mkdf-ig-image mkdf-item-space \">\n\t\t\t\t<div class=\"mkdf-ig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-02.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-178]\" title=\"collefrisio-gallery-02\">\n\t\t\t\t\t\t\t\t\t\t\t<img width=\"1500\" height=\"998\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-02.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-02.jpg 1500w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-02-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-02-1024x681.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-02-768x511.jpg 768w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-02-600x399.jpg 600w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"mkdf-ig-image mkdf-item-space \">\n\t\t\t\t<div class=\"mkdf-ig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/01\/collefrisio-gallery-16.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-178]\" title=\"collefrisio-gallery-16\">\n\t\t\t\t\t\t\t\t\t\t\t<img width=\"1500\" height=\"562\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/01\/collefrisio-gallery-16.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/01\/collefrisio-gallery-16.jpg 1500w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/01\/collefrisio-gallery-16-300x112.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/01\/collefrisio-gallery-16-1024x384.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/01\/collefrisio-gallery-16-768x288.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"mkdf-ig-image mkdf-item-space \">\n\t\t\t\t<div class=\"mkdf-ig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-03.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-178]\" title=\"collefrisio-gallery-03\">\n\t\t\t\t\t\t\t\t\t\t\t<img width=\"1500\" height=\"998\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-03.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-03.jpg 1500w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-03-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-03-1024x681.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-03-768x511.jpg 768w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-03-600x399.jpg 600w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"mkdf-ig-image mkdf-item-space \">\n\t\t\t\t<div class=\"mkdf-ig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-04.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-178]\" title=\"collefrisio-gallery-04\">\n\t\t\t\t\t\t\t\t\t\t\t<img width=\"1500\" height=\"998\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-04.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-04.jpg 1500w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-04-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-04-1024x681.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-04-768x511.jpg 768w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-04-600x399.jpg 600w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"mkdf-ig-image mkdf-item-space \">\n\t\t\t\t<div class=\"mkdf-ig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-14.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-178]\" title=\"collefrisio-gallery-14\">\n\t\t\t\t\t\t\t\t\t\t\t<img width=\"1423\" height=\"679\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-14.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-14.jpg 1423w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-14-300x143.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-14-1024x489.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-14-768x366.jpg 768w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-14-600x286.jpg 600w\" sizes=\"(max-width: 1423px) 100vw, 1423px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"mkdf-ig-image mkdf-item-space \">\n\t\t\t\t<div class=\"mkdf-ig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-05.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-178]\" title=\"collefrisio-gallery-05\">\n\t\t\t\t\t\t\t\t\t\t\t<img width=\"1500\" height=\"998\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-05.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-05.jpg 1500w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-05-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-05-1024x681.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-05-768x511.jpg 768w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-05-600x399.jpg 600w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"mkdf-ig-image mkdf-item-space \">\n\t\t\t\t<div class=\"mkdf-ig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/01\/collefrisio-gallery-18.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-178]\" title=\"collefrisio-gallery-18\">\n\t\t\t\t\t\t\t\t\t\t\t<img width=\"1800\" height=\"309\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/01\/collefrisio-gallery-18.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/01\/collefrisio-gallery-18.jpg 1800w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/01\/collefrisio-gallery-18-300x52.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/01\/collefrisio-gallery-18-1024x176.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/01\/collefrisio-gallery-18-768x132.jpg 768w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2022\/01\/collefrisio-gallery-18-1536x264.jpg 1536w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"mkdf-ig-image mkdf-item-space \">\n\t\t\t\t<div class=\"mkdf-ig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-10.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-178]\" title=\"collefrisio-gallery-10\">\n\t\t\t\t\t\t\t\t\t\t\t<img width=\"1500\" height=\"998\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-10.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-10.jpg 1500w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-10-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-10-1024x681.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-10-768x511.jpg 768w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-10-600x399.jpg 600w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"mkdf-ig-image mkdf-item-space \">\n\t\t\t\t<div class=\"mkdf-ig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-06.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-178]\" title=\"collefrisio-gallery-06\">\n\t\t\t\t\t\t\t\t\t\t\t<img width=\"1500\" height=\"998\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-06.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-06.jpg 1500w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-06-300x200.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-06-1024x681.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-06-768x511.jpg 768w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-06-600x399.jpg 600w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"mkdf-ig-image mkdf-item-space \">\n\t\t\t\t<div class=\"mkdf-ig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"mkdf-ig-lightbox\" href=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-13.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-178]\" title=\"collefrisio-gallery-13\">\n\t\t\t\t\t\t\t\t\t\t\t<img width=\"1630\" height=\"679\" src=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-13.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-13.jpg 1630w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-13-300x125.jpg 300w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-13-1024x427.jpg 1024w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-13-768x320.jpg 768w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-13-1536x640.jpg 1536w, https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-gallery-13-600x250.jpg 600w\" sizes=\"(max-width: 1630px) 100vw, 1630px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row el_class=&#8221;gallery-first-row&#8221;][vc_column offset=&#8221;vc_col-lg-offset-1 vc_col-lg-10&#8243;][vc_empty_space][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text] Interview to Amedeo De Luca &#8211; Founder [\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text] Interview with Antonio Patricelli part 1 &#8211; Founder [\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text] Interview to Antonio Patricelli part 2 &#8211; Founder [\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row row_content_width=&#8221;grid&#8221; el_class=&#8221;gallery-sec-row&#8221;][vc_column][vc_empty_space][\/vc_column][\/vc_row][vc_row el_class=&#8221;gallery-third-row&#8221;][vc_column offset=&#8221;vc_col-lg-offset-1 vc_col-lg-10&#8243;][vc_empty_space][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gallery - Collefrisio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.collefrisio.it\/en\/gallery\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gallery - Collefrisio\" \/>\n<meta property=\"og:description\" content=\"[vc_row el_class=&#8221;gallery-first-row&#8221;][vc_column offset=&#8221;vc_col-lg-offset-1 vc_col-lg-10&#8243;][vc_empty_space][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text] Interview to Amedeo De Luca &#8211; Founder [\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text] Interview with Antonio Patricelli part 1 &#8211; Founder [\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text] Interview to Antonio Patricelli part 2 &#8211; Founder [\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row row_content_width=&#8221;grid&#8221; el_class=&#8221;gallery-sec-row&#8221;][vc_column][vc_empty_space][\/vc_column][\/vc_row][vc_row el_class=&#8221;gallery-third-row&#8221;][vc_column offset=&#8221;vc_col-lg-offset-1 vc_col-lg-10&#8243;][vc_empty_space][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.collefrisio.it\/en\/gallery\/\" \/>\n<meta property=\"og:site_name\" content=\"Collefrisio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/it-it.facebook.com\/collefrisio\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-05T10:22:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.collefrisio.it\/#organization\",\"name\":\"Collefrisio SRL\",\"url\":\"https:\/\/www.collefrisio.it\/\",\"sameAs\":[\"https:\/\/it-it.facebook.com\/collefrisio\",\"https:\/\/www.instagram.com\/collefrisiowine\/?hl=it\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.collefrisio.it\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-logo-full-big.png\",\"contentUrl\":\"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-logo-full-big.png\",\"width\":400,\"height\":255,\"caption\":\"Collefrisio SRL\"},\"image\":{\"@id\":\"https:\/\/www.collefrisio.it\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.collefrisio.it\/#website\",\"url\":\"https:\/\/www.collefrisio.it\/\",\"name\":\"Collefrisio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.collefrisio.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.collefrisio.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.collefrisio.it\/en\/gallery\/#webpage\",\"url\":\"https:\/\/www.collefrisio.it\/en\/gallery\/\",\"name\":\"Gallery - Collefrisio\",\"isPartOf\":{\"@id\":\"https:\/\/www.collefrisio.it\/#website\"},\"datePublished\":\"2022-04-05T10:11:52+00:00\",\"dateModified\":\"2022-04-05T10:22:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.collefrisio.it\/en\/gallery\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.collefrisio.it\/en\/gallery\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.collefrisio.it\/en\/gallery\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.collefrisio.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gallery\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gallery - Collefrisio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.collefrisio.it\/en\/gallery\/","og_locale":"en_US","og_type":"article","og_title":"Gallery - Collefrisio","og_description":"[vc_row el_class=&#8221;gallery-first-row&#8221;][vc_column offset=&#8221;vc_col-lg-offset-1 vc_col-lg-10&#8243;][vc_empty_space][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text] Interview to Amedeo De Luca &#8211; Founder [\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text] Interview with Antonio Patricelli part 1 &#8211; Founder [\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text] Interview to Antonio Patricelli part 2 &#8211; Founder [\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row row_content_width=&#8221;grid&#8221; el_class=&#8221;gallery-sec-row&#8221;][vc_column][vc_empty_space][\/vc_column][\/vc_row][vc_row el_class=&#8221;gallery-third-row&#8221;][vc_column offset=&#8221;vc_col-lg-offset-1 vc_col-lg-10&#8243;][vc_empty_space][\/vc_column][\/vc_row]","og_url":"https:\/\/www.collefrisio.it\/en\/gallery\/","og_site_name":"Collefrisio","article_publisher":"https:\/\/it-it.facebook.com\/collefrisio","article_modified_time":"2022-04-05T10:22:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.collefrisio.it\/#organization","name":"Collefrisio SRL","url":"https:\/\/www.collefrisio.it\/","sameAs":["https:\/\/it-it.facebook.com\/collefrisio","https:\/\/www.instagram.com\/collefrisiowine\/?hl=it"],"logo":{"@type":"ImageObject","@id":"https:\/\/www.collefrisio.it\/#logo","inLanguage":"en-US","url":"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-logo-full-big.png","contentUrl":"https:\/\/www.collefrisio.it\/wp-content\/uploads\/2021\/06\/collefrisio-logo-full-big.png","width":400,"height":255,"caption":"Collefrisio SRL"},"image":{"@id":"https:\/\/www.collefrisio.it\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.collefrisio.it\/#website","url":"https:\/\/www.collefrisio.it\/","name":"Collefrisio","description":"","publisher":{"@id":"https:\/\/www.collefrisio.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.collefrisio.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.collefrisio.it\/en\/gallery\/#webpage","url":"https:\/\/www.collefrisio.it\/en\/gallery\/","name":"Gallery - Collefrisio","isPartOf":{"@id":"https:\/\/www.collefrisio.it\/#website"},"datePublished":"2022-04-05T10:11:52+00:00","dateModified":"2022-04-05T10:22:34+00:00","breadcrumb":{"@id":"https:\/\/www.collefrisio.it\/en\/gallery\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.collefrisio.it\/en\/gallery\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.collefrisio.it\/en\/gallery\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.collefrisio.it\/en\/"},{"@type":"ListItem","position":2,"name":"Gallery"}]}]}},"_links":{"self":[{"href":"https:\/\/www.collefrisio.it\/en\/wp-json\/wp\/v2\/pages\/5244"}],"collection":[{"href":"https:\/\/www.collefrisio.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.collefrisio.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.collefrisio.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collefrisio.it\/en\/wp-json\/wp\/v2\/comments?post=5244"}],"version-history":[{"count":4,"href":"https:\/\/www.collefrisio.it\/en\/wp-json\/wp\/v2\/pages\/5244\/revisions"}],"predecessor-version":[{"id":5248,"href":"https:\/\/www.collefrisio.it\/en\/wp-json\/wp\/v2\/pages\/5244\/revisions\/5248"}],"wp:attachment":[{"href":"https:\/\/www.collefrisio.it\/en\/wp-json\/wp\/v2\/media?parent=5244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}